{"id":556,"count":4,"description":"Canapele si Fotolii Bolivia","link":"https:\/\/mobiladeluxonline.ro\/en\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/","name":"Bolivia canapele si fotolii","slug":"bolivia-canapele-si-fotolii","taxonomy":"product_cat","parent":40,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arhive Bolivia canapele si fotolii - MobilaDeLuxOnline.ro<\/title>\n<meta name=\"description\" content=\"Bolivia canapele extensibile si fotolii. Coltare extensibile\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobiladeluxonline.ro\/en\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhive Bolivia canapele si fotolii - MobilaDeLuxOnline.ro\" \/>\n<meta property=\"og:description\" content=\"Bolivia canapele extensibile si fotolii. Coltare extensibile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobiladeluxonline.ro\/en\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/\" \/>\n<meta property=\"og:site_name\" content=\"MobilaDeLuxOnline.ro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/cat\\\/mobila-clasica\\\/canapele-si-coltare\\\/bolivia-canapele-si-fotolii\\\/\",\"url\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/cat\\\/mobila-clasica\\\/canapele-si-coltare\\\/bolivia-canapele-si-fotolii\\\/\",\"name\":\"Arhive Bolivia canapele si fotolii - MobilaDeLuxOnline.ro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/#website\"},\"description\":\"Bolivia canapele extensibile si fotolii. Coltare extensibile\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/cat\\\/mobila-clasica\\\/canapele-si-coltare\\\/bolivia-canapele-si-fotolii\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/cat\\\/mobila-clasica\\\/canapele-si-coltare\\\/bolivia-canapele-si-fotolii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MOBILA CLASICA\",\"item\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/cat\\\/mobila-clasica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Canapele si coltare\",\"item\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/cat\\\/mobila-clasica\\\/canapele-si-coltare\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bolivia canapele si fotolii\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/#website\",\"url\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/\",\"name\":\"MobilaDeLuxOnline.ro\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mobiladeluxonline.ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhive Bolivia canapele si fotolii - MobilaDeLuxOnline.ro","description":"Bolivia canapele extensibile si fotolii. Coltare extensibile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobiladeluxonline.ro\/en\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/","og_locale":"en_US","og_type":"article","og_title":"Arhive Bolivia canapele si fotolii - MobilaDeLuxOnline.ro","og_description":"Bolivia canapele extensibile si fotolii. Coltare extensibile","og_url":"https:\/\/mobiladeluxonline.ro\/en\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/","og_site_name":"MobilaDeLuxOnline.ro","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mobiladeluxonline.ro\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/","url":"https:\/\/mobiladeluxonline.ro\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/","name":"Arhive Bolivia canapele si fotolii - MobilaDeLuxOnline.ro","isPartOf":{"@id":"https:\/\/mobiladeluxonline.ro\/#website"},"description":"Bolivia canapele extensibile si fotolii. Coltare extensibile","breadcrumb":{"@id":"https:\/\/mobiladeluxonline.ro\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mobiladeluxonline.ro\/cat\/mobila-clasica\/canapele-si-coltare\/bolivia-canapele-si-fotolii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/mobiladeluxonline.ro\/"},{"@type":"ListItem","position":2,"name":"MOBILA CLASICA","item":"https:\/\/mobiladeluxonline.ro\/cat\/mobila-clasica\/"},{"@type":"ListItem","position":3,"name":"Canapele si coltare","item":"https:\/\/mobiladeluxonline.ro\/cat\/mobila-clasica\/canapele-si-coltare\/"},{"@type":"ListItem","position":4,"name":"Bolivia canapele si fotolii"}]},{"@type":"WebSite","@id":"https:\/\/mobiladeluxonline.ro\/#website","url":"https:\/\/mobiladeluxonline.ro\/","name":"MobilaDeLuxOnline.ro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobiladeluxonline.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mobiladeluxonline.ro\/en\/wp-json\/wp\/v2\/product_cat\/556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobiladeluxonline.ro\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mobiladeluxonline.ro\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mobiladeluxonline.ro\/en\/wp-json\/wp\/v2\/product_cat\/40"}],"wp:post_type":[{"href":"https:\/\/mobiladeluxonline.ro\/en\/wp-json\/wp\/v2\/product?product_cat=556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}